{"id":14097,"date":"2018-09-04T11:52:35","date_gmt":"2018-09-04T18:52:35","guid":{"rendered":"https:\/\/sashacarrion.com\/?p=14097"},"modified":"2022-05-10T06:58:59","modified_gmt":"2022-05-10T13:58:59","slug":"marijuana-use-in-teens-and-young-adults","status":"publish","type":"post","link":"https:\/\/www.sashacarrion.com\/es\/2018\/09\/04\/marijuana-use-in-teens-and-young-adults\/","title":{"rendered":"Uso de Marihuana en Adolescentes y J\u00f3venes Adultos"},"content":{"rendered":"<\/p>\n<div class=\"ast-oembed-container\" style=\"height: 100%;\"><iframe title=\"Uso de Marihuana en Adolescentes y J\u00f3venes Adultos\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Q2T04P1dMwU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>\n<p>&nbsp;<\/p>\n<p>Uso de Marihuana en Adolescentes y J\u00f3venes Adultos<\/p>\n<p>Antes de nada, quiero decir que de ninguna manera estoy en contra del uso de la marihuana, especialmente en adultos mayores que pueden beneficiarse de ella, entiendo que le sirve a mucha gente y yo misma creo que deber\u00eda ser legal. Ahora que he dicho esto, quiero mencionar algo que cada vez m\u00e1s, estoy viendo en mi oficina.<\/p>\n<p>Tengo padres que vienen con adolescentes y adultos j\u00f3venes que llegan porque sus hijos est\u00e1n muy mal debido a su consumo de marihuana. Cada vez que un padre desesperado llama debido al consumo de marihuana de su hijo, generalmente me dicen lo siguiente: Mi hijo no hace nada, siempre est\u00e1 encerrado en su habitaci\u00f3n fumando o saliendo con sus amigos en vez de estudiar o trabajar. Est\u00e1 aumentando mucho peso. Se ha vuelto cada vez m\u00e1s paranoico. Ahora incluso comenz\u00f3 a escuchar voces. El psiquiatra que acaba de ver dice que tiene sintomas de esquizofrenia y a\u00fan con con eso, no quiere dejarlo. Necesita dejarlo. Ayud\u00e9le.<br \/>\nSiempre le explico a los padres, normalmente a la madre, que nuestras sesiones solo funcionan si la persona quiere lo que est\u00e1 buscando. Si no quieren dejar de dejar de fumar, las posibilidades de que mis sesiones funcionen se reducen a la mitad.<\/p>\n<p>Un adulto joven recientemente me dijo que pod\u00eda reducir su ingesta de marihuana pero que no estaba completamente listo para dejar de fumar. En su siguiente cita, dijo que se hab\u00eda dado cuenta de que era totalmente adicto a ella y que ten\u00eda que dejarlo. Gastaba todo su dinero en fumar y \u00e9l mismo se daba cuenta de que estaba decepcionado con si mismo porque no estaba haciendo nada para llegar a sus metas. Estaba perdiendo el tiempo. Por cierto, las personas entre las edades de 15 a 24 a\u00f1os tienen mayores tasas de consumo de marihuana que las personas mayores de 25 a\u00f1os. Los estudios tambi\u00e9n han demostrado que el consumo temprano puede afectar realmente a los adultos j\u00f3venes no solo en su capacidad para alcanzar metas, sino tambi\u00e9n mentalmente. Incluso, la estructura de su cerebro se altera. Un estudio demostr\u00f3 que aquellos que usaban marihuana intensamente, para la edad de 18 a\u00f1os ten\u00edan 6 veces m\u00e1s probabilidades de desarrollar esquizofrenia que aquellos que no la usaban. Por supuesto que habr\u00e1 otros factores que deben tenerse en cuenta, como los antecedentes familiares y los traumas infantiles. Sin embargo, hay una conexi\u00f3n entre ambas cosas que no se puede negar.<\/p>\n<p>Ahora, no estoy diciendo que este sea el caso de todo adolescente o adulto joven que est\u00e9 fumando marihuana porque no creo que sea as\u00ed. Lo que estoy se\u00f1alando es que algunos adolescentes y adultos j\u00f3venes pueden sufrir mucho m\u00e1s los efectos nocivos del consumo frecuente de marihuana. Podr\u00edas pensar que esto se debe m\u00e1s al tipo de cultivo que est\u00e9n fumando, a la cepa particular, y que deber\u00edan consumir otra. Yo no tengo la respuesta a eso, pero lo que s\u00ed s\u00e9 es lo que estoy viendo en mi oficina.<\/p>\n<p>He escuchado a la gente decir que la marihuana no es adictiva. Para ciertas personas, s\u00ed lo es. De hecho, los adolescentes y los adultos j\u00f3venes son m\u00e1s propensos a volverse adictos que los adultos mayores, lo que puede hacer que ayudar a un ni\u00f1o sea a\u00fan m\u00e1s dif\u00edcil si \u00e9l o ella est\u00e1n realmente enganchados. Un estudio particular dijo que 1 de cada 6 adolescentes que usan marihuana desarrollar\u00e1 una adicci\u00f3n. Para los usuarios diarios, del 25 al 50% se volver\u00e1n adictos.<\/p>\n<p>Si eres un padre o madre preocupado que est\u00e1 viviendo algunas de las cosas que mencion\u00e9, lo mejor que puedes hacer es comenzar a hablar con tu hijo y hacer todo lo posible para mantener la conversaci\u00f3n lo m\u00e1s tranquila posible. Ten en cuenta que cuanto m\u00e1s presiones con el tema, mayores ser\u00e1n las posibilidades de que tu hijo se enfade por lo que hay que actuar estrat\u00e9gicamente sin intentar ser controlador.<\/p>\n<p>\u00bfTe ha resultado \u00fatil este video? Si es as\u00ed, dale un me gusta y no te olvide de visitar <a href=\"https:\/\/sashacarrion.com\/best-hypnosis\/children-teenagers-adolescent\/\" target=\"_blank\" rel=\"noopener\">mi website<\/a> para m\u00e1s informaci\u00f3n. \u00a1Nos vemos pronto!<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Marijuana use in teens and young adults Before I continue with this video, I want to say that I am in no way against the use of marijuana particularly by mature adults who are able to benefit from it. I understand that it does a lot of people good. I myself think it\u2019s something [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1045,196,30],"tags":[3630,3631,2518,3632,3633,2516,2515,2517,2514,2513,1279,3634,3635,3636,3637,2519,2520,2521,2522,3638],"class_list":["post-14097","post","type-post","status-publish","format-standard","hentry","category-bad-habits","category-children-teenagers","category-hypnosis","tag-abuso-de-drogas","tag-abuso-de-drogas-en-adolescentes-y-adultos-jovenes","tag-addiction-in-teenagers","tag-adiccion-en-adolescentes","tag-consumo-de-marihuana","tag-drug-abuse","tag-drug-abuse-in-teens-and-young-adults","tag-marijuana-consumption","tag-marijuana-use","tag-marijuana-use-in-teens-and-young-adults","tag-sasha-carrion","tag-tratamiento-para-adolescentes","tag-tratamiento-para-adultos-jovenes","tag-tratamiento-para-la-adiccion","tag-tratamiento-para-la-adiccion-a-la-marihuana","tag-treatment-for-addiction","tag-treatment-for-marijuana-addiction","tag-treatment-for-teenagers","tag-treatment-for-young-adults","tag-uso-de-marihuana-en-adolescentes-y-jovenes-adultos-consumo-de-marihuana"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/posts\/14097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/comments?post=14097"}],"version-history":[{"count":4,"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/posts\/14097\/revisions"}],"predecessor-version":[{"id":26957,"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/posts\/14097\/revisions\/26957"}],"wp:attachment":[{"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/media?parent=14097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/categories?post=14097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sashacarrion.com\/es\/wp-json\/wp\/v2\/tags?post=14097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}